{"id":600,"date":"2011-09-12T11:24:36","date_gmt":"2011-09-12T09:24:36","guid":{"rendered":"http:\/\/kettentechnik.de\/?p=600"},"modified":"2023-02-09T15:46:15","modified_gmt":"2023-02-09T13:46:15","slug":"einfach-kettenraeder-10b-1-din-8187","status":"publish","type":"post","link":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/","title":{"rendered":"Einfach-Kettenr\u00e4der 10B-1 DIN 8187"},"content":{"rendered":"<div id=\"picturemiddle\">\n<div class=\"product_image\"><a href=\"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2011\/09\/kettenradeinfach1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-7265\" src=\"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2011\/09\/kettenradeinfach1-300x288.jpg\" alt=\"einfach kettenrad 10B-1 DIN 8187\" width=\"300\" height=\"288\" srcset=\"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2011\/09\/kettenradeinfach1-300x288.jpg 300w, https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2011\/09\/kettenradeinfach1.jpg 595w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<\/div>\n<div>Kettenr\u00e4der 10B-1:<\/div>\n<div><\/div>\n<ul>\n<li>ISO-Nr.: 10 B-1 (5\/8\u201c x 3\/8\u201c)<\/li>\n<\/ul>\n<ul>\n<li>Teilung: 15,875 mm<\/li>\n<\/ul>\n<ul>\n<li>lichte Weite: 9,65 mm<\/li>\n<\/ul>\n<ul>\n<li>Rollen-Durchmesser: 10,16 mm<\/li>\n<\/ul>\n<ul>\n<li>Zahnbreite bf1 9,1 mm<\/li>\n<\/ul>\n<ul>\n<li>ba 1,6 mm (Abfasung der Zahnbreite)<\/li>\n<\/ul>\n<ul>\n<li>rx 16 mm (min. Zahnfasenradius)<\/li>\n<\/ul>\n<table style=\"width: 107.666%; height: 1109px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<thead>\n<tr style=\"height: 39px;\">\n<td style=\"height: 39px;\" width=\"53\">\n<p align=\"center\">unsere<\/p>\n<\/td>\n<td style=\"height: 39px;\" width=\"53\">\n<p align=\"center\">Z\u00e4hne-<\/p>\n<\/td>\n<td style=\"height: 39px;\" width=\"54\">\n<p align=\"center\">Teilkreis<\/p>\n<\/td>\n<td style=\"height: 39px;\" width=\"52\">\n<p align=\"center\">Kopfkreis<\/p>\n<\/td>\n<td style=\"height: 39px;\" width=\"55\">\n<p align=\"center\">Naben<\/p>\n<\/td>\n<td style=\"height: 39px;\" width=\"69\">\n<p align=\"center\">Vorbohrung<\/p>\n<\/td>\n<td style=\"height: 39px;\" width=\"52\">\n<p align=\"center\">Bohrung<\/p>\n<p align=\"center\">\n<\/td>\n<td style=\"height: 39px;\" width=\"47\">\n<p align=\"center\">Gesamt<\/p>\n<\/td>\n<td style=\"height: 39px;\" width=\"60\">\n<p align=\"center\">Gewicht<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 20px;\">\n<td style=\"height: 20px;\" width=\"53\">\n<p align=\"center\">Art.Nr.<\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"53\">\n<p align=\"center\">zahl<\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"54\">\n<p align=\"center\">\u00d8<\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"52\">\n<p align=\"center\">\u00d8<\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"55\">\n<p align=\"center\">\u00d8<\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"69\">\n<p align=\"center\">\u00d8<\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"52\">\n<p align=\"center\">max.<\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"47\">\n<p align=\"center\">l\u00e4nge<\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"60\">\n<p align=\"center\">ca.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 20px;\">\n<td style=\"height: 20px;\" width=\"53\"><\/td>\n<td style=\"height: 20px;\" width=\"53\">\n<p align=\"center\"><strong>z<\/strong><\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"54\">\n<p align=\"center\"><strong>d<sub>0<\/sub><\/strong><\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"52\">\n<p align=\"center\"><strong>d<sub>k<\/sub><\/strong><\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"55\">\n<p align=\"center\"><strong>d<sub>n<\/sub><\/strong><\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"69\">\n<p align=\"center\"><strong>d<sub>1<\/sub><\/strong><\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"52\">\n<p align=\"center\"><strong>d<sub>2<\/sub><\/strong><\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"47\">\n<p align=\"center\"><strong>L<\/strong><\/p>\n<\/td>\n<td style=\"height: 20px;\" width=\"60\">\n<p align=\"center\"><strong>kg<\/strong><\/p>\n<\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\"><\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 42px;\">\n<td style=\"height: 42px;\" width=\"53\"><\/td>\n<td style=\"height: 42px;\" width=\"53\">\n<p align=\"center\"><strong>Material Stahl\/C45<\/strong><\/p>\n<\/td>\n<td style=\"height: 42px;\" width=\"54\"><\/td>\n<td style=\"height: 42px;\" width=\"52\"><\/td>\n<td style=\"height: 42px;\" width=\"55\"><\/td>\n<td style=\"height: 42px;\" width=\"69\"><\/td>\n<td style=\"height: 42px;\" width=\"52\"><\/td>\n<td style=\"height: 42px;\" width=\"47\"><\/td>\n<td style=\"height: 42px;\" width=\"60\"><\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1057\/kettenrad-10b-1-z-08-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-08<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=1930\" target=\"_blank\" rel=\"noopener\">8<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">41,48<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">47<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">25<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">10<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">15<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">25<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,12<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1058\/kettenrad-10b-1-z-09-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-09<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=1931\" target=\"_blank\" rel=\"noopener\">9<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">46,42<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">53<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">10<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">18<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">25<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,16<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1059\/kettenrad-10b-1-z-10-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-10<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=210\" target=\"_blank\" rel=\"noopener\">10<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">51,4<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">58<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">10<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">25<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,18<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1060\/kettenrad-10b-1-z-11-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-11<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=284\" target=\"_blank\" rel=\"noopener\">11<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">56,3<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">63<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">37<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">12<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">23<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,26<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1061\/kettenrad-10b-1-z-12-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-12<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=285\" target=\"_blank\" rel=\"noopener\">12<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">61,3<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">68<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">42<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">12<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">26<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,32<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1062\/kettenrad-10b-1-z-13-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-13<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=286\" target=\"_blank\" rel=\"noopener\">13<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">66,3<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">73<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">47<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">12<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">29<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,40<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1063\/kettenrad-10b-1-z-14-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-14<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=287\" target=\"_blank\" rel=\"noopener\">14<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">71,3<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">78<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">52<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">12<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">32<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,49<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 18px;\">\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"54\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"55\"><\/td>\n<td style=\"height: 18px;\" width=\"69\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"47\"><\/td>\n<td style=\"height: 18px;\" width=\"60\"><\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1064\/kettenrad-10b-1-z-15-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-15<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=288\" target=\"_blank\" rel=\"noopener\">15<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">76,4<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">83<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">57<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">12<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,58<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1065\/kettenrad-10b-1-z-16-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-16<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=289\" target=\"_blank\" rel=\"noopener\">16<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">81,4<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">88<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">60<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">12<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">38<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,74<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1066\/kettenrad-10b-1-z-17-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-17<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=290\" target=\"_blank\" rel=\"noopener\">17<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">86,4<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">93<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">60<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">12<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">38<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,78<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1067\/kettenrad-10b-1-z-18-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-18<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=291\" target=\"_blank\" rel=\"noopener\">18<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">91,4<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">98<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">70<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">14<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">44<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,83<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1068\/kettenrad-10b-1-z-19-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-19<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=292\" target=\"_blank\" rel=\"noopener\">19<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">96,5<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">103<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">70<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">14<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">44<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,88<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 18px;\">\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"54\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"55\"><\/td>\n<td style=\"height: 18px;\" width=\"69\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"47\"><\/td>\n<td style=\"height: 18px;\" width=\"60\"><\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1069\/kettenrad-10b-1-z-20-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-20<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=293\" target=\"_blank\" rel=\"noopener\">20<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">101,5<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">108<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">75<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">14<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">47<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">0,93<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1070\/kettenrad-10b-1-z-21-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-21<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=294\" target=\"_blank\" rel=\"noopener\">21<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">106,5<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">113<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">80<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">16<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">47<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">1,15<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1071\/kettenrad-10b-1-z-22-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-22<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=295\" target=\"_blank\" rel=\"noopener\">22<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">111,6<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">118<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">80<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">16<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">50<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">1,21<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1072\/kettenrad-10b-1-z-23-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-23<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=296\" target=\"_blank\" rel=\"noopener\">23<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">116,6<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">123<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">80<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">16<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">50<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">1,27<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1073\/kettenrad-10b-1-z-24-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-24<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=297\" target=\"_blank\" rel=\"noopener\">24<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">121,6<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">128<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">80<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">16<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">50<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">1,33<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 18px;\">\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"54\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"55\"><\/td>\n<td style=\"height: 18px;\" width=\"69\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"47\"><\/td>\n<td style=\"height: 18px;\" width=\"60\"><\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1075\/kettenrad-10b-1-z-25-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-25<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=298\" target=\"_blank\" rel=\"noopener\">25<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">126,7<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">134<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">85<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">50<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">30<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">1,39<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1076\/kettenrad-10b-1-z-26-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-26<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=299\" target=\"_blank\" rel=\"noopener\">26<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">131,7<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">139<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">85<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">53<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">1,81<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/5329\/kettenrad-10b-1-z-27-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-27<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=300\" target=\"_blank\" rel=\"noopener\">27<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">136,7<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">144<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">90<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">53<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">1,88<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1078\/kettenrad-10b-1-z-28-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-28<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=301\" target=\"_blank\" rel=\"noopener\">28<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">141,8<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">148<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">90<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">56<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">1,98<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1074\/kettenrad-10b-1-z-29-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-29<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=302\" target=\"_blank\" rel=\"noopener\">29<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">146,8<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">154<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">90<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">56<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,06<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 18px;\">\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"54\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"55\"><\/td>\n<td style=\"height: 18px;\" width=\"69\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"47\"><\/td>\n<td style=\"height: 18px;\" width=\"60\"><\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1079\/kettenrad-10b-1-z-30-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-30<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=303\" target=\"_blank\" rel=\"noopener\">30<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">151,9<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">159<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">90<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">56<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,10<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1080\/kettenrad-10b-1-z-31-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-31<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=304\" target=\"_blank\" rel=\"noopener\">31<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">156,9<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">164<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">95<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">60<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,19<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1081\/kettenrad-10b-1-z-32-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-32<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=305\" target=\"_blank\" rel=\"noopener\">32<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">162,0<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">169<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">95<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">60<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,27<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1082\/kettenrad-10b-1-z-33-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-33<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=306\" target=\"_blank\" rel=\"noopener\">33<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">167,0<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">174<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">95<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">60<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,31<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1083\/kettenrad-10b-1-z-34-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-34<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=307\" target=\"_blank\" rel=\"noopener\">34<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">172,1<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">179<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">95<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">60<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,45<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 18px;\">\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"54\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"55\"><\/td>\n<td style=\"height: 18px;\" width=\"69\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"47\"><\/td>\n<td style=\"height: 18px;\" width=\"60\"><\/td>\n<\/tr>\n<tr style=\"height: 22.6167px;\">\n<td style=\"height: 22px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1084\/kettenrad-10b-1-z-35-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-35<\/a><\/p>\n<\/td>\n<td style=\"height: 22px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=308\" target=\"_blank\" rel=\"noopener\">35<\/a><\/p>\n<\/td>\n<td style=\"height: 22px;\" width=\"54\">\n<p align=\"center\">177,1<\/p>\n<\/td>\n<td style=\"height: 22px;\" width=\"52\">\n<p align=\"center\">184<\/p>\n<\/td>\n<td style=\"height: 22px;\" width=\"55\">\n<p align=\"center\">95<\/p>\n<\/td>\n<td style=\"height: 22px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 22px;\" width=\"52\">\n<p align=\"center\">60<\/p>\n<\/td>\n<td style=\"height: 22px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 22px;\" width=\"60\">\n<p align=\"center\">2,54<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1085\/kettenrad-10b-1-z-36-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-36<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=309\" target=\"_blank\" rel=\"noopener\">36<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">182,1<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">189<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">100<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">63<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,63<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1086\/kettenrad-10b-1-z-37-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-37<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=310\" target=\"_blank\" rel=\"noopener\">37<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">187,2<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">194<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">100<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">63<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,72<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1087\/kettenrad-10b-1-z-38-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-38<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=311\" target=\"_blank\" rel=\"noopener\">38<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">192,2<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">199<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">100<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">63<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,81<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1089\/kettenrad-10b-1-z-39-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-39<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=312\" target=\"_blank\" rel=\"noopener\">39<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">197,2<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">204<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">100<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">63<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">2,95<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 18px;\">\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"54\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"55\"><\/td>\n<td style=\"height: 18px;\" width=\"69\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"47\"><\/td>\n<td style=\"height: 18px;\" width=\"60\"><\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1090\/kettenrad-10b-1-z-40-vorgeb.?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-40<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=313\" target=\"_blank\" rel=\"noopener\">40<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">202,3<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">209<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">100<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">63<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">35<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">3,10<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 18px;\">\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"53\"><\/td>\n<td style=\"height: 18px;\" width=\"54\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"55\"><\/td>\n<td style=\"height: 18px;\" width=\"69\"><\/td>\n<td style=\"height: 18px;\" width=\"52\"><\/td>\n<td style=\"height: 18px;\" width=\"47\"><\/td>\n<td style=\"height: 18px;\" width=\"60\"><\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\"><\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><strong>Material GG20<\/strong><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\"><\/td>\n<td style=\"height: 21px;\" width=\"52\"><\/td>\n<td style=\"height: 21px;\" width=\"55\"><\/td>\n<td style=\"height: 21px;\" width=\"69\"><\/td>\n<td style=\"height: 21px;\" width=\"52\"><\/td>\n<td style=\"height: 21px;\" width=\"47\"><\/td>\n<td style=\"height: 21px;\" width=\"60\"><\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">KR10B-1-38GG<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">38<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">192,2<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">200<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">80<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">19<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">45<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">40<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">3,90<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">KR10B-1-45GG<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">45<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">227,6<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">235<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">80<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">19<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">45<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">40<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">4,20<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">KR10B-1-57GG<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">57<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">288,2<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">296<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">90<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">23<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">50<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">45<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">5,25<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">KR10B-1-76GG<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">76<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">384,2<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">392<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">90<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">23<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">50<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">50<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">7,10<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"https:\/\/www.kettentechnik-shop.de\/kettenraeder\/kettenraeder-mit-nabe\/einfach-kettenraeder\/kettenrad-10b-1\/1056\/kettenrad-10b-1-z-95-vorgeb.-material-grauguss?c=140\" target=\"_blank\" rel=\"noopener\">KR10B-1-95GG<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\"><a href=\"http:\/\/www.kettentechnik-shop.de\/product_info.php?cPath=199_200_201_225&amp;products_id=63779\" target=\"_blank\" rel=\"noopener\">95<\/a><\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">480,1<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">488<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">100<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">23<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">55<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">56<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">10,00<\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">KR10B-1-114GG<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"53\">\n<p align=\"center\">114<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"54\">\n<p align=\"center\">576,13<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">584,1<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"55\">\n<p align=\"center\">100<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"69\">\n<p align=\"center\">23<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"52\">\n<p align=\"center\">55<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"47\">\n<p align=\"center\">56<\/p>\n<\/td>\n<td style=\"height: 21px;\" width=\"60\">\n<p align=\"center\">14,50<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kettenr\u00e4der 10B-1: ISO-Nr.: 10 B-1 (5\/8\u201c x 3\/8\u201c) Teilung: 15,875 mm lichte Weite: 9,65 mm Rollen-Durchmesser: 10,16 mm Zahnbreite bf1 9,1 mm ba 1,6 mm (Abfasung der Zahnbreite) rx 16 mm (min. Zahnfasenradius) unsere Z\u00e4hne- Teilkreis Kopfkreis Naben Vorbohrung Bohrung &hellip; <a href=\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":6371,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[215],"tags":[108,116,120,129,131,134,136,137,138,139,141,142,163,166,169,170,173,175,180,181,185,189,190,194,195,206],"class_list":["post-600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einfach-kettenraeder-simplex","tag-din-8187","tag-din8187","tag-en818","tag-groshandler","tag-hersteller","tag-hochleistungsrollenkette","tag-industriekette","tag-industrieketten","tag-iso-606","tag-iso606","tag-katalog","tag-kaufen","tag-langlebig","tag-lieferant","tag-online-kaufen","tag-onlineshop","tag-rolenkette","tag-rollenkete","tag-rollenlketten-shop","tag-roller-chain","tag-shop","tag-tec","tag-tec-kette","tag-umlenkrad","tag-umlenkritzel","tag-zulieferer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Einfach-Kettenr\u00e4der 10B-1 DIN 8187 - Deutsch<\/title>\n<meta name=\"description\" content=\"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 vom kompetenten Partner aus Vorrat. Einfach-Kettenr\u00e4der 10B-1 DIN 8187 schnelle Lieferung - g\u00fcnstige Preise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 - Deutsch\" \/>\n<meta property=\"og:description\" content=\"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 vom kompetenten Partner aus Vorrat. Einfach-Kettenr\u00e4der 10B-1 DIN 8187 schnelle Lieferung - g\u00fcnstige Preise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/KTS-Kettentechnik-GmbH\/411832932300884?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-12T09:24:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-09T13:46:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"100\" \/>\n\t<meta property=\"og:image:height\" content=\"116\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"carolin.hasselbrink\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Kettentechnik\" \/>\n<meta name=\"twitter:site\" content=\"@Kettentechnik\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"carolin.hasselbrink\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/\"},\"author\":{\"name\":\"carolin.hasselbrink\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#\/schema\/person\/13f0f6cf3a8abf7a5811fab9a519d758\"},\"headline\":\"Einfach-Kettenr\u00e4der 10B-1 DIN 8187\",\"datePublished\":\"2011-09-12T09:24:36+00:00\",\"dateModified\":\"2023-02-09T13:46:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/\"},\"wordCount\":182,\"publisher\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg\",\"keywords\":[\"DIN 8187\",\"DIN8187\",\"en818\",\"gro\u00dfh\u00e4ndler\",\"Hersteller\",\"hochleistungsrollenkette\",\"industriekette\",\"Industrieketten\",\"ISO 606\",\"iso606\",\"katalog\",\"kaufen\",\"langlebig\",\"Lieferant\",\"online kaufen\",\"onlineshop\",\"rolenkette\",\"rollenkete\",\"rollenlketten shop\",\"roller chain\",\"shop\",\"tec\",\"tec kette\",\"umlenkrad\",\"umlenkritzel\",\"zulieferer\"],\"articleSection\":[\"Einfach-Kettenr\u00e4der (Simplex)\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/\",\"url\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/\",\"name\":\"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 - Deutsch\",\"isPartOf\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg\",\"datePublished\":\"2011-09-12T09:24:36+00:00\",\"dateModified\":\"2023-02-09T13:46:15+00:00\",\"description\":\"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 vom kompetenten Partner aus Vorrat. Einfach-Kettenr\u00e4der 10B-1 DIN 8187 schnelle Lieferung - g\u00fcnstige Preise.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#primaryimage\",\"url\":\"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg\",\"contentUrl\":\"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg\",\"width\":100,\"height\":116},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kettentechnik.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einfach-Kettenr\u00e4der 10B-1 DIN 8187\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#website\",\"url\":\"https:\/\/www.kettentechnik.de\/de\/\",\"name\":\"Deutsch\",\"description\":\"Rollenketten und Kettenr\u00e4der aus Vorrat\",\"publisher\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kettentechnik.de\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#organization\",\"name\":\"KTS Kettentechnik GmbH\",\"url\":\"https:\/\/www.kettentechnik.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2015\/08\/KTS_logo_freigestellt.gif\",\"contentUrl\":\"http:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2015\/08\/KTS_logo_freigestellt.gif\",\"width\":785,\"height\":368,\"caption\":\"KTS Kettentechnik GmbH\"},\"image\":{\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pages\/KTS-Kettentechnik-GmbH\/411832932300884?fref=ts\",\"https:\/\/x.com\/Kettentechnik\",\"https:\/\/www.linkedin.com\/company\/6205865?trk=tyah&amp;amp;amp;trkInfo=clickedVertical:company,clickedEntityId:6205865,idx:2-1-2,tarId:1464766025858,tas:kts ket\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#\/schema\/person\/13f0f6cf3a8abf7a5811fab9a519d758\",\"name\":\"carolin.hasselbrink\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kettentechnik.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a352afa5f56581086ad38007b2e205fd503c8755490785feee7c5b7e9e66bd36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a352afa5f56581086ad38007b2e205fd503c8755490785feee7c5b7e9e66bd36?s=96&d=mm&r=g\",\"caption\":\"carolin.hasselbrink\"},\"url\":\"https:\/\/www.kettentechnik.de\/de\/author\/carolin-hasselbrink\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 - Deutsch","description":"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 vom kompetenten Partner aus Vorrat. Einfach-Kettenr\u00e4der 10B-1 DIN 8187 schnelle Lieferung - g\u00fcnstige Preise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/","og_locale":"de_DE","og_type":"article","og_title":"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 - Deutsch","og_description":"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 vom kompetenten Partner aus Vorrat. Einfach-Kettenr\u00e4der 10B-1 DIN 8187 schnelle Lieferung - g\u00fcnstige Preise.","og_url":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/","og_site_name":"Deutsch","article_publisher":"https:\/\/www.facebook.com\/pages\/KTS-Kettentechnik-GmbH\/411832932300884?fref=ts","article_published_time":"2011-09-12T09:24:36+00:00","article_modified_time":"2023-02-09T13:46:15+00:00","og_image":[{"width":100,"height":116,"url":"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg","type":"image\/jpeg"}],"author":"carolin.hasselbrink","twitter_card":"summary_large_image","twitter_creator":"@Kettentechnik","twitter_site":"@Kettentechnik","twitter_misc":{"Verfasst von":"carolin.hasselbrink","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#article","isPartOf":{"@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/"},"author":{"name":"carolin.hasselbrink","@id":"https:\/\/www.kettentechnik.de\/de\/#\/schema\/person\/13f0f6cf3a8abf7a5811fab9a519d758"},"headline":"Einfach-Kettenr\u00e4der 10B-1 DIN 8187","datePublished":"2011-09-12T09:24:36+00:00","dateModified":"2023-02-09T13:46:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/"},"wordCount":182,"publisher":{"@id":"https:\/\/www.kettentechnik.de\/de\/#organization"},"image":{"@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg","keywords":["DIN 8187","DIN8187","en818","gro\u00dfh\u00e4ndler","Hersteller","hochleistungsrollenkette","industriekette","Industrieketten","ISO 606","iso606","katalog","kaufen","langlebig","Lieferant","online kaufen","onlineshop","rolenkette","rollenkete","rollenlketten shop","roller chain","shop","tec","tec kette","umlenkrad","umlenkritzel","zulieferer"],"articleSection":["Einfach-Kettenr\u00e4der (Simplex)"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/","url":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/","name":"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 - Deutsch","isPartOf":{"@id":"https:\/\/www.kettentechnik.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#primaryimage"},"image":{"@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg","datePublished":"2011-09-12T09:24:36+00:00","dateModified":"2023-02-09T13:46:15+00:00","description":"Einfach-Kettenr\u00e4der 10B-1 DIN 8187 vom kompetenten Partner aus Vorrat. Einfach-Kettenr\u00e4der 10B-1 DIN 8187 schnelle Lieferung - g\u00fcnstige Preise.","breadcrumb":{"@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#primaryimage","url":"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg","contentUrl":"https:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2013\/06\/Kopie-von-KRSS.jpg","width":100,"height":116},{"@type":"BreadcrumbList","@id":"https:\/\/www.kettentechnik.de\/de\/2011\/09\/12\/einfach-kettenraeder-10b-1-din-8187\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kettentechnik.de\/de\/"},{"@type":"ListItem","position":2,"name":"Einfach-Kettenr\u00e4der 10B-1 DIN 8187"}]},{"@type":"WebSite","@id":"https:\/\/www.kettentechnik.de\/de\/#website","url":"https:\/\/www.kettentechnik.de\/de\/","name":"Deutsch","description":"Rollenketten und Kettenr\u00e4der aus Vorrat","publisher":{"@id":"https:\/\/www.kettentechnik.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kettentechnik.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kettentechnik.de\/de\/#organization","name":"KTS Kettentechnik GmbH","url":"https:\/\/www.kettentechnik.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kettentechnik.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2015\/08\/KTS_logo_freigestellt.gif","contentUrl":"http:\/\/www.kettentechnik.de\/de\/wp-content\/uploads\/sites\/2\/2015\/08\/KTS_logo_freigestellt.gif","width":785,"height":368,"caption":"KTS Kettentechnik GmbH"},"image":{"@id":"https:\/\/www.kettentechnik.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/KTS-Kettentechnik-GmbH\/411832932300884?fref=ts","https:\/\/x.com\/Kettentechnik","https:\/\/www.linkedin.com\/company\/6205865?trk=tyah&amp;amp;amp;trkInfo=clickedVertical:company,clickedEntityId:6205865,idx:2-1-2,tarId:1464766025858,tas:kts ket"]},{"@type":"Person","@id":"https:\/\/www.kettentechnik.de\/de\/#\/schema\/person\/13f0f6cf3a8abf7a5811fab9a519d758","name":"carolin.hasselbrink","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kettentechnik.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a352afa5f56581086ad38007b2e205fd503c8755490785feee7c5b7e9e66bd36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a352afa5f56581086ad38007b2e205fd503c8755490785feee7c5b7e9e66bd36?s=96&d=mm&r=g","caption":"carolin.hasselbrink"},"url":"https:\/\/www.kettentechnik.de\/de\/author\/carolin-hasselbrink\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/posts\/600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/comments?post=600"}],"version-history":[{"count":39,"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/posts\/600\/revisions"}],"predecessor-version":[{"id":9548,"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/posts\/600\/revisions\/9548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/media\/6371"}],"wp:attachment":[{"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/media?parent=600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/categories?post=600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kettentechnik.de\/de\/wp-json\/wp\/v2\/tags?post=600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}